{"id":776,"date":"2021-08-17T13:01:20","date_gmt":"2021-08-17T18:01:20","guid":{"rendered":"https:\/\/www.zanjarajuno.org\/?page_id=776"},"modified":"2026-08-20T20:21:16","modified_gmt":"2026-08-21T01:21:16","slug":"encuentro-de-saberes","status":"publish","type":"page","link":"https:\/\/www.zanjarajuno.org\/fr\/rencontre-de-connaissance\/","title":{"rendered":"Rencontre de la connaissance"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><div      class=\"vc_row wpb_row section vc_row-fluid  vc_custom_1622158779402 grid_section\" style=' text-align:left;'><div class=\"section_inner clearfix\"><div class='section_inner_margin clearfix'><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"qode-advanced-tabs qode-advanced-tabs qode-advanced-horizontal-tab clearfix qode-advanced-tab-without-icon qode-advanced-tabs-column-3 clearfix\">\n\t<ul class=\"qode-advanced-tabs-nav\">\n\t\t\t\t\t<li>\n\t\t\t\t<h5>\n\t\t\t\t\t<a href=\"#tab-biblioteca\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"qode-advanced-tab-text-after-icon\">\n\t\t\t\t\t\t\t\tBIBLIOTH\u00c8QUE\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t<\/h5>\n\t\t\t<\/li>\n\t\t\t\t\t<li>\n\t\t\t\t<h5>\n\t\t\t\t\t<a href=\"#tab-chacra-demostrativa\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"qode-advanced-tab-text-after-icon\">\n\t\t\t\t\t\t\t\tFERME DE D\u00c9MONSTRATION\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t<\/h5>\n\t\t\t<\/li>\n\t\t\t\t\t<li>\n\t\t\t\t<h5>\n\t\t\t\t\t<a href=\"#tab-misiones-de-biodiversidad\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"qode-advanced-tab-text-after-icon\">\n\t\t\t\t\t\t\t\tMISSIONS SUR LA BIODIVERSIT\u00c9\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t<\/h5>\n\t\t\t<\/li>\n\t\t\t<\/ul>\n\t<div class=\"qode-advanced-tab-container\" id=\"tab-biblioteca-474\" data-icon-pack=\"\" data-icon-html=\"\"><div class=\"wpb_gallery wpb_content_element vc_clearfix\"><div class=\"wpb_wrapper\"><div class=\"wpb_gallery_slides wpb_flexslider flexslider_slide flexslider\" data-interval=\"0\" data-flex_fx=\"slide\"><ul class=\"slides\"><li><a itemprop=\"image\" class=\"qode-prettyphoto\" href=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/04\/inauguracion.jpg\" data-rel=\"prettyPhoto[rel-776-624060086]\"><img loading=\"lazy\" decoding=\"async\" width=\"842\" height=\"595\" src=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/04\/inauguracion.jpg\" class=\"attachment-large\" alt=\"\" title=\"ouverture\" srcset=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/04\/inauguracion.jpg 842w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/04\/inauguracion-18x12.jpg 18w\" sizes=\"auto, (max-width: 842px) 100vw, 842px\" \/><\/a><\/li><li><a itemprop=\"image\" class=\"qode-prettyphoto\" href=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/04\/dsc-0178-1024x683.jpg\" data-rel=\"prettyPhoto[rel-776-624060086]\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/04\/dsc-0178-1024x683.jpg\" class=\"attachment-large\" alt=\"\" title=\"DSC_0178\" srcset=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/04\/dsc-0178-1024x683.jpg 1024w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/04\/dsc-0178-1536x1024.jpg 1536w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/04\/dsc-0178-18x12.jpg 18w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/04\/dsc-0178.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/li><li><a itemprop=\"image\" class=\"qode-prettyphoto\" href=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2024\/08\/img-20211211-wa0020-e1725245086840-1024x574.jpg\" data-rel=\"prettyPhoto[rel-776-624060086]\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"574\" src=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2024\/08\/img-20211211-wa0020-e1725245086840-1024x574.jpg\" class=\"attachment-large\" alt=\"\" title=\"IMG-20211211-WA0020\" srcset=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2024\/08\/img-20211211-wa0020-e1725245086840-1024x574.jpg 1024w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2024\/08\/img-20211211-wa0020-e1725245086840-18x10.jpg 18w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2024\/08\/img-20211211-wa0020-e1725245086840.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/li><li><a itemprop=\"image\" class=\"qode-prettyphoto\" href=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2024\/08\/whatsapp-image-2024-08-31-at-4.07.41-pm-e1725246363127-1024x576.jpeg\" data-rel=\"prettyPhoto[rel-776-624060086]\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2024\/08\/whatsapp-image-2024-08-31-at-4.07.41-pm-e1725246363127-1024x576.jpeg\" class=\"attachment-large\" alt=\"\" title=\"WhatsApp Image 2024-08-31 \u00e0 4.07.41 PM\" srcset=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2024\/08\/whatsapp-image-2024-08-31-at-4.07.41-pm-e1725246363127-1024x576.jpeg 1024w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2024\/08\/whatsapp-image-2024-08-31-at-4.07.41-pm-e1725246363127-18x10.jpeg 18w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2024\/08\/whatsapp-image-2024-08-31-at-4.07.41-pm-e1725246363127.jpeg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/li><li><a itemprop=\"image\" class=\"qode-prettyphoto\" href=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2024\/05\/WhatsApp-Image-2024-05-30-at-1.26.36-PM-e1725255414259-1024x576.jpeg\" data-rel=\"prettyPhoto[rel-776-624060086]\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2024\/05\/WhatsApp-Image-2024-05-30-at-1.26.36-PM-e1725255414259-1024x576.jpeg\" class=\"attachment-large\" alt=\"\" title=\"WhatsApp Image 2024-05-30 \u00e0 1.26.36 PM\" srcset=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2024\/05\/WhatsApp-Image-2024-05-30-at-1.26.36-PM-e1725255414259-1024x576.jpeg 1024w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2024\/05\/WhatsApp-Image-2024-05-30-at-1.26.36-PM-e1725255414259-18x10.jpeg 18w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2024\/05\/WhatsApp-Image-2024-05-30-at-1.26.36-PM-e1725255414259.jpeg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/li><li><a itemprop=\"image\" class=\"qode-prettyphoto\" href=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2024\/05\/IMG-20211211-WA0023-e1717026689243-1024x577.jpg\" data-rel=\"prettyPhoto[rel-776-624060086]\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"577\" src=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2024\/05\/IMG-20211211-WA0023-e1717026689243-1024x577.jpg\" class=\"attachment-large\" alt=\"\" title=\"IMG-20211211-WA0023\" srcset=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2024\/05\/IMG-20211211-WA0023-e1717026689243-1024x577.jpg 1024w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2024\/05\/IMG-20211211-WA0023-e1717026689243-18x10.jpg 18w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2024\/05\/IMG-20211211-WA0023-e1717026689243.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/li><li><a itemprop=\"image\" class=\"qode-prettyphoto\" href=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/04\/dsc-0112-1024x683.jpg\" data-rel=\"prettyPhoto[rel-776-624060086]\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/04\/dsc-0112-1024x683.jpg\" class=\"attachment-large\" alt=\"\" title=\"DSC_0112\" srcset=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/04\/dsc-0112-1024x683.jpg 1024w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/04\/dsc-0112-1536x1024.jpg 1536w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/04\/dsc-0112-18x12.jpg 18w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/04\/dsc-0112.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/li><li><a itemprop=\"image\" class=\"qode-prettyphoto\" href=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/04\/dsc-0129-1-1024x683.jpg\" data-rel=\"prettyPhoto[rel-776-624060086]\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/04\/dsc-0129-1-1024x683.jpg\" class=\"attachment-large\" alt=\"\" title=\"DSC_0129\" srcset=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/04\/dsc-0129-1-1024x683.jpg 1024w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/04\/dsc-0129-1-1536x1024.jpg 1536w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/04\/dsc-0129-1-18x12.jpg 18w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/04\/dsc-0129-1.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/li><li><a itemprop=\"image\" class=\"qode-prettyphoto\" href=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/04\/dsc-0144-1024x683.jpg\" data-rel=\"prettyPhoto[rel-776-624060086]\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/04\/dsc-0144-1024x683.jpg\" class=\"attachment-large\" alt=\"\" title=\"DSC_0144\" srcset=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/04\/dsc-0144-1024x683.jpg 1024w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/04\/dsc-0144-1536x1024.jpg 1536w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/04\/dsc-0144-18x12.jpg 18w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/04\/dsc-0144.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/li><li><a itemprop=\"image\" class=\"qode-prettyphoto\" href=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/04\/dsc-0181-1024x683.jpg\" data-rel=\"prettyPhoto[rel-776-624060086]\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/04\/dsc-0181-1024x683.jpg\" class=\"attachment-large\" alt=\"\" title=\"DSC_0181\" srcset=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/04\/dsc-0181-1024x683.jpg 1024w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/04\/dsc-0181-1536x1024.jpg 1536w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/04\/dsc-0181-18x12.jpg 18w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/04\/dsc-0181.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/li><\/ul><\/div><\/div><\/div>\n\t<div class=\"wpb_text_column wpb_content_element\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"text-align: justify;\"><strong>CONTEXTE<\/strong><\/p>\n<p style=\"text-align: justify;\">La biblioth\u00e8que \"Yachay Wasi\" est n\u00e9e de l'amour de la lecture et des livres que Medardo Tapia (son fondateur) manifeste avec passion et inspiration, de l'amour des enfants et de l'amour des mains laborieuses qui cultivent les champs et habitent la for\u00eat amazonienne. C'est un espace ouvert o\u00f9 des ateliers et des r\u00e9unions de toutes sortes ont \u00e9t\u00e9 organis\u00e9s : ateliers de th\u00e9\u00e2tre pour enfants, recherche sur la biodiversit\u00e9, processus de formation pour les paysans, les peuples et les nationalit\u00e9s, sur des th\u00e8mes tels que l'agro\u00e9cologie, l'\u00e9ducation \u00e0 l'environnement, la violence \u00e0 l'\u00e9gard des femmes, etc... .... Nous voulons qu'elle devienne un v\u00e9ritable rendez-vous de la connaissance, o\u00f9 ses livres soient non seulement un instrument pr\u00e9cieux pour la transmission, le renforcement et la diffusion du savoir, mais servent \u00e9galement \u00e0 encourager la lecture \u00e0 des fins purement r\u00e9cr\u00e9atives et satisfaisantes.<\/p>\n<p style=\"text-align: justify;\">Bien que le principal moteur du travail effectu\u00e9 ait \u00e9t\u00e9 la protection et la conservation de la nature, il ne serait pas complet s'il n'abordait pas l'\u00eatre social et ses r\u00e9alit\u00e9s. C'est pourquoi le contenu a \u00e9t\u00e9 \u00e9tendu \u00e0 la sph\u00e8re sociale, en abordant des questions telles que la migration et la r\u00e9alit\u00e9 socio-\u00e9conomique, qui sont essentielles pour d\u00e9velopper une strat\u00e9gie de conservation dans laquelle les connaissances ancestrales et les connaissances occidentales s'entrem\u00ealent. Gr\u00e2ce \u00e0 la lecture et \u00e0 des activit\u00e9s ludiques, un outil attrayant d'apprentissage et de sensibilisation a \u00e9t\u00e9 cr\u00e9\u00e9.<\/p>\n<p style=\"text-align: justify;\"><strong>\u00a0<\/strong><\/p>\n\n\t\t<\/div> \n\t<\/div> <div class=\"wpb_gallery wpb_content_element vc_clearfix\"><div class=\"wpb_wrapper\"><div class=\"wpb_gallery_slides wpb_flexslider flexslider_fade flexslider\" data-interval=\"3\" data-flex_fx=\"fade\"><ul class=\"slides\"><li><a itemprop=\"image\" class=\"qode-prettyphoto\" href=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/04\/mesa-de-trabajo-1.png\" data-rel=\"prettyPhoto[rel-776-1200529985]\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"212\" src=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/04\/mesa-de-trabajo-1.png\" class=\"attachment-medium\" alt=\"\" title=\"Tableau de travail 1\" srcset=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/04\/mesa-de-trabajo-1.png 843w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/04\/mesa-de-trabajo-1-18x12.png 18w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/li><li><a itemprop=\"image\" class=\"qode-prettyphoto\" href=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/02\/whatsapp-image-2025-02-10-at-2.38.04-pm-1-1024x683.jpeg\" data-rel=\"prettyPhoto[rel-776-1200529985]\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/02\/whatsapp-image-2025-02-10-at-2.38.04-pm-1.jpeg\" class=\"attachment-medium\" alt=\"\" title=\"WhatsApp Image 2025-02-10 \u00e0 2.38.04 PM (1)\" srcset=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/02\/whatsapp-image-2025-02-10-at-2.38.04-pm-1.jpeg 1500w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/02\/whatsapp-image-2025-02-10-at-2.38.04-pm-1-1024x683.jpeg 1024w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/02\/whatsapp-image-2025-02-10-at-2.38.04-pm-1-18x12.jpeg 18w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/li><li><a itemprop=\"image\" class=\"qode-prettyphoto\" href=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/04\/dsc-0127-1024x683.jpg\" data-rel=\"prettyPhoto[rel-776-1200529985]\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/04\/dsc-0127.jpg\" class=\"attachment-medium\" alt=\"\" title=\"DSC_0127\" srcset=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/04\/dsc-0127.jpg 1920w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/04\/dsc-0127-1024x683.jpg 1024w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/04\/dsc-0127-1536x1024.jpg 1536w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/04\/dsc-0127-18x12.jpg 18w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/li><li><a itemprop=\"image\" class=\"qode-prettyphoto\" href=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/02\/whatsapp-image-2025-02-10-at-2.38.07-pm-1-1024x683.jpeg\" data-rel=\"prettyPhoto[rel-776-1200529985]\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/02\/whatsapp-image-2025-02-10-at-2.38.07-pm-1.jpeg\" class=\"attachment-medium\" alt=\"\" title=\"WhatsApp Image 2025-02-10 \u00e0 2.38.07 PM (1)\" srcset=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/02\/whatsapp-image-2025-02-10-at-2.38.07-pm-1.jpeg 1500w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/02\/whatsapp-image-2025-02-10-at-2.38.07-pm-1-1024x683.jpeg 1024w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/02\/whatsapp-image-2025-02-10-at-2.38.07-pm-1-18x12.jpeg 18w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/li><li><a itemprop=\"image\" class=\"qode-prettyphoto\" href=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/02\/img-20250208-095520-1024x576.jpg\" data-rel=\"prettyPhoto[rel-776-1200529985]\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" src=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/02\/img-20250208-095520.jpg\" class=\"attachment-medium\" alt=\"\" title=\"IMG_20250208_095520\" srcset=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/02\/img-20250208-095520.jpg 1920w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/02\/img-20250208-095520-1024x576.jpg 1024w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/02\/img-20250208-095520-1536x864.jpg 1536w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/02\/img-20250208-095520-18x10.jpg 18w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/li><li><a itemprop=\"image\" class=\"qode-prettyphoto\" href=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/02\/img-20250125-101743-1024x574.jpg\" data-rel=\"prettyPhoto[rel-776-1200529985]\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"168\" src=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/02\/img-20250125-101743.jpg\" class=\"attachment-medium\" alt=\"\" title=\"IMG_20250125_101743\" srcset=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/02\/img-20250125-101743.jpg 1920w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/02\/img-20250125-101743-1024x574.jpg 1024w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/02\/img-20250125-101743-1536x862.jpg 1536w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/02\/img-20250125-101743-18x10.jpg 18w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/li><li><a itemprop=\"image\" class=\"qode-prettyphoto\" href=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/02\/img-20250125-110830-1024x771.jpg\" data-rel=\"prettyPhoto[rel-776-1200529985]\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"226\" src=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/02\/img-20250125-110830.jpg\" class=\"attachment-medium\" alt=\"\" title=\"IMG_20250125_110830\" srcset=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/02\/img-20250125-110830.jpg 1920w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/02\/img-20250125-110830-1024x771.jpg 1024w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/02\/img-20250125-110830-1536x1157.jpg 1536w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/02\/img-20250125-110830-16x12.jpg 16w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/li><li><a itemprop=\"image\" class=\"qode-prettyphoto\" href=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/02\/img-20250125-140928-1-1024x771.jpg\" data-rel=\"prettyPhoto[rel-776-1200529985]\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"226\" src=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/02\/img-20250125-140928-1.jpg\" class=\"attachment-medium\" alt=\"\" title=\"IMG_20250125_140928 (1)\" srcset=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/02\/img-20250125-140928-1.jpg 1920w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/02\/img-20250125-140928-1-1024x771.jpg 1024w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/02\/img-20250125-140928-1-1536x1157.jpg 1536w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/02\/img-20250125-140928-1-16x12.jpg 16w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/li><li><a itemprop=\"image\" class=\"qode-prettyphoto\" href=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/02\/dsc-0110-1024x683.jpg\" data-rel=\"prettyPhoto[rel-776-1200529985]\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/02\/dsc-0110.jpg\" class=\"attachment-medium\" alt=\"\" title=\"DSC_0110\" srcset=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/02\/dsc-0110.jpg 1920w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/02\/dsc-0110-1024x683.jpg 1024w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/02\/dsc-0110-1536x1024.jpg 1536w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/02\/dsc-0110-18x12.jpg 18w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/li><li><a itemprop=\"image\" class=\"qode-prettyphoto\" href=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/02\/dsc-0025-1024x683.jpg\" data-rel=\"prettyPhoto[rel-776-1200529985]\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/02\/dsc-0025.jpg\" class=\"attachment-medium\" alt=\"\" title=\"DSC_0025\" srcset=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/02\/dsc-0025.jpg 1920w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/02\/dsc-0025-1024x683.jpg 1024w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/02\/dsc-0025-1536x1024.jpg 1536w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/02\/dsc-0025-18x12.jpg 18w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/li><li><a itemprop=\"image\" class=\"qode-prettyphoto\" href=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/02\/dsc-0038-1024x683.jpg\" data-rel=\"prettyPhoto[rel-776-1200529985]\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/02\/dsc-0038.jpg\" class=\"attachment-medium\" alt=\"\" title=\"DSC_0038\" srcset=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/02\/dsc-0038.jpg 1920w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/02\/dsc-0038-1024x683.jpg 1024w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/02\/dsc-0038-1536x1024.jpg 1536w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/02\/dsc-0038-18x12.jpg 18w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/li><li><a itemprop=\"image\" class=\"qode-prettyphoto\" href=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/02\/dsc-0075-1024x683.jpg\" data-rel=\"prettyPhoto[rel-776-1200529985]\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/02\/dsc-0075.jpg\" class=\"attachment-medium\" alt=\"\" title=\"DSC_0075\" srcset=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/02\/dsc-0075.jpg 1920w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/02\/dsc-0075-1024x683.jpg 1024w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/02\/dsc-0075-1536x1024.jpg 1536w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/02\/dsc-0075-18x12.jpg 18w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/li><li><a itemprop=\"image\" class=\"qode-prettyphoto\" href=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/02\/dsc-0088-1024x683.jpg\" data-rel=\"prettyPhoto[rel-776-1200529985]\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/02\/dsc-0088.jpg\" class=\"attachment-medium\" alt=\"\" title=\"DSC_0088\" srcset=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/02\/dsc-0088.jpg 1920w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/02\/dsc-0088-1024x683.jpg 1024w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/02\/dsc-0088-1536x1024.jpg 1536w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/02\/dsc-0088-18x12.jpg 18w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/li><li><a itemprop=\"image\" class=\"qode-prettyphoto\" href=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/04\/dsc-0114-1024x683.jpg\" data-rel=\"prettyPhoto[rel-776-1200529985]\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/04\/dsc-0114.jpg\" class=\"attachment-medium\" alt=\"\" title=\"DSC_0114\" srcset=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/04\/dsc-0114.jpg 1920w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/04\/dsc-0114-1024x683.jpg 1024w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/04\/dsc-0114-1536x1024.jpg 1536w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/04\/dsc-0114-18x12.jpg 18w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/li><li><a itemprop=\"image\" class=\"qode-prettyphoto\" href=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/04\/dsc-0123-1024x683.jpg\" data-rel=\"prettyPhoto[rel-776-1200529985]\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/04\/dsc-0123.jpg\" class=\"attachment-medium\" alt=\"\" title=\"DSC_0123\" srcset=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/04\/dsc-0123.jpg 1920w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/04\/dsc-0123-1024x683.jpg 1024w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/04\/dsc-0123-1536x1024.jpg 1536w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/04\/dsc-0123-18x12.jpg 18w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/li><li><a itemprop=\"image\" class=\"qode-prettyphoto\" href=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/04\/dsc-0126-1024x683.jpg\" data-rel=\"prettyPhoto[rel-776-1200529985]\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/04\/dsc-0126.jpg\" class=\"attachment-medium\" alt=\"\" title=\"DSC_0126\" srcset=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/04\/dsc-0126.jpg 1920w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/04\/dsc-0126-1024x683.jpg 1024w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/04\/dsc-0126-1536x1024.jpg 1536w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/04\/dsc-0126-18x12.jpg 18w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/li><li><a itemprop=\"image\" class=\"qode-prettyphoto\" href=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/04\/dsc-0128-1024x683.jpg\" data-rel=\"prettyPhoto[rel-776-1200529985]\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/04\/dsc-0128.jpg\" class=\"attachment-medium\" alt=\"\" title=\"DSC_0128\" srcset=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/04\/dsc-0128.jpg 1920w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/04\/dsc-0128-1024x683.jpg 1024w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/04\/dsc-0128-1536x1024.jpg 1536w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/04\/dsc-0128-18x12.jpg 18w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/li><li><a itemprop=\"image\" class=\"qode-prettyphoto\" href=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/04\/dsc-0142-1024x683.jpg\" data-rel=\"prettyPhoto[rel-776-1200529985]\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/04\/dsc-0142.jpg\" class=\"attachment-medium\" alt=\"\" title=\"DSC_0142\" srcset=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/04\/dsc-0142.jpg 1920w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/04\/dsc-0142-1024x683.jpg 1024w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/04\/dsc-0142-1536x1024.jpg 1536w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/04\/dsc-0142-18x12.jpg 18w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/li><li><a itemprop=\"image\" class=\"qode-prettyphoto\" href=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/04\/dsc-0150-1024x683.jpg\" data-rel=\"prettyPhoto[rel-776-1200529985]\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/04\/dsc-0150.jpg\" class=\"attachment-medium\" alt=\"\" title=\"DSC_0150\" srcset=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/04\/dsc-0150.jpg 1920w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/04\/dsc-0150-1024x683.jpg 1024w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/04\/dsc-0150-1536x1024.jpg 1536w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/04\/dsc-0150-18x12.jpg 18w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/li><li><a itemprop=\"image\" class=\"qode-prettyphoto\" href=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/04\/dsc-0158-1024x683.jpg\" data-rel=\"prettyPhoto[rel-776-1200529985]\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/04\/dsc-0158.jpg\" class=\"attachment-medium\" alt=\"\" title=\"DSC_0158\" srcset=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/04\/dsc-0158.jpg 1920w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/04\/dsc-0158-1024x683.jpg 1024w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/04\/dsc-0158-1536x1024.jpg 1536w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/04\/dsc-0158-18x12.jpg 18w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/li><\/ul><\/div><\/div><\/div>\n\t<div class=\"wpb_text_column wpb_content_element\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"text-align: justify;\">Ce travail a permis de cr\u00e9er le\u00a0<strong>la n\u00e9cessit\u00e9 de cr\u00e9er un espace de lecture<\/strong>C'\u00e9tait un lieu ouvert \u00e0 tous, enfants, adolescents, membres de la communaut\u00e9 et visiteurs de toutes sortes qui pouvaient y trouver un livre qui attirait leur attention. Des livres ont \u00e9t\u00e9 r\u00e9cup\u00e9r\u00e9s dans des centres de recyclage qui allaient \u00eatre d\u00e9truits, nous avons re\u00e7u des dons de la part de visiteurs qui venaient \u00e0 Zanja Arajuno et, peu \u00e0 peu, l'id\u00e9e d'une biblioth\u00e8que en plein air a commenc\u00e9 \u00e0 \u00e9merger, lisant un livre tout en profitant de la nature, ou disposant d'un guide de terrain pour identifier une esp\u00e8ce biologique. Un espace pour les jeunes et les moins jeunes. Petit \u00e0 petit, nous avons pu rassembler des livres de diff\u00e9rents types pour constituer la biblioth\u00e8que et promouvoir cette initiative, en\u00a0<strong>En 2021, un Tambo de lectura a \u00e9t\u00e9 cr\u00e9\u00e9 dans la communaut\u00e9 de Mariscal Sucre,<\/strong> o\u00f9 Roberto Guerrero (@osvaldo.guerra00) a dirig\u00e9 ce processus en tant que m\u00e9diateur de lecture.  Les Tambos de Lectura sont une initiative du minist\u00e8re de la culture et du patrimoine, dans le cadre du Plan national du livre et de la lecture Jos\u00e9 de la Cuadra, et dans le cadre de la coop\u00e9ration interinstitutionnelle avec l'Organisation des \u00c9tats ib\u00e9ro-am\u00e9ricains pour l'\u00e9ducation, la science et la culture (OEI). Il s'agit d'espaces de m\u00e9diation de la lecture situ\u00e9s dans des endroits strat\u00e9giques en raison de leur situation g\u00e9ographique et de leur capacit\u00e9 \u00e0 rassembler des communaut\u00e9s qui ont g\u00e9n\u00e9ralement \u00e9t\u00e9 rel\u00e9gu\u00e9es en dehors des instances de lecture. Environ 17 enfants de la communaut\u00e9 ont particip\u00e9 au processus, qui a \u00e9t\u00e9 tr\u00e8s bien accueilli. Les enfants ont pris part \u00e0 des activit\u00e9s ludiques qui encourageaient la lecture et ont commenc\u00e9 \u00e0 emprunter des livres \u00e0 la maison afin que cet int\u00e9r\u00eat pour la lecture ait un impact sur le noyau familial.<\/p>\n<p style=\"text-align: justify;\">Ce processus a permis de r\u00e9unir des talents divers et des r\u00eaves communs, et de renforcer l'id\u00e9e de consolider la biblioth\u00e8que et d'am\u00e9liorer son service \u00e0 l'ensemble de la communaut\u00e9.<\/p>\n<p style=\"text-align: justify;\"><strong>\u00a0<\/strong><\/p>\n\n\t\t<\/div> \n\t<\/div> \n\t<div class=\"wpb_text_column wpb_content_element\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n\t\t<\/div> \n\t<\/div> <div class=\"wpb_gallery wpb_content_element vc_clearfix\"><div class=\"wpb_wrapper\"><div class=\"wpb_gallery_slides wpb_image_grid\" data-interval=\"3\"><div class=\"gallery_holder\"><ul class=\"gallery_inner gallery_with_space  v5\"><li class=\"no_grayscale\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"140\" src=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/02\/whatsapp-image-2025-02-11-at-2.51.48-pm-removebg-preview.png\" class=\"attachment-medium\" alt=\"\" title=\"WhatsApp_Image_2025-02-11_at_2.51.48_PM-removebg-preview\" srcset=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/02\/whatsapp-image-2025-02-11-at-2.51.48-pm-removebg-preview.png 690w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/02\/whatsapp-image-2025-02-11-at-2.51.48-pm-removebg-preview-18x8.png 18w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/li><li class=\"no_grayscale\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/02\/sachateca-color.png\" class=\"attachment-medium\" alt=\"\" title=\"COULEUR SACHATECA\" srcset=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/02\/sachateca-color.png 1080w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/02\/sachateca-color-1024x1024.png 1024w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/02\/sachateca-color-150x150.png 150w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/02\/sachateca-color-12x12.png 12w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/li><li class=\"no_grayscale\"><img loading=\"lazy\" decoding=\"async\" width=\"188\" height=\"112\" src=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/02\/pa.png\" class=\"attachment-medium\" alt=\"\" title=\"pa\" srcset=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/02\/pa.png 188w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/02\/pa-18x12.png 18w\" sizes=\"auto, (max-width: 188px) 100vw, 188px\" \/><\/li><li class=\"no_grayscale\"><img loading=\"lazy\" decoding=\"async\" width=\"259\" height=\"194\" src=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/02\/lanceros-removebg-preview.png\" class=\"attachment-medium\" alt=\"\" title=\"lanceros-removebg-preview\" srcset=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/02\/lanceros-removebg-preview.png 259w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/02\/lanceros-removebg-preview-16x12.png 16w\" sizes=\"auto, (max-width: 259px) 100vw, 259px\" \/><\/li><\/ul><\/div><\/div><\/div><\/div><\/div><div class=\"qode-advanced-tab-container\" id=\"tab-chacra-demostrativa-695\" data-icon-pack=\"\" data-icon-html=\"\"><div class=\"wpb_gallery wpb_content_element vc_clearfix\"><div class=\"wpb_wrapper\"><div class=\"wpb_gallery_slides wpb_flexslider flexslider_fade flexslider\" data-interval=\"3\" data-flex_fx=\"fade\"><ul class=\"slides\"><li><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"135\" src=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2024\/09\/img-20230901-133844.jpg\" class=\"attachment-medium\" alt=\"\" title=\"IMG_20230901_133844\" srcset=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2024\/09\/img-20230901-133844.jpg 1920w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2024\/09\/img-20230901-133844-1024x461.jpg 1024w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2024\/09\/img-20230901-133844-1536x691.jpg 1536w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2024\/09\/img-20230901-133844-18x8.jpg 18w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"135\" src=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2024\/09\/img-20230714-090400.jpg\" class=\"attachment-medium\" alt=\"\" title=\"IMG_20230714_090400\" srcset=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2024\/09\/img-20230714-090400.jpg 1920w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2024\/09\/img-20230714-090400-1024x461.jpg 1024w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2024\/09\/img-20230714-090400-1536x691.jpg 1536w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2024\/09\/img-20230714-090400-18x8.jpg 18w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"135\" src=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2024\/05\/mujeres-Mariscal-2-e1717120863186.jpg\" class=\"attachment-medium\" alt=\"\" title=\"femmes Mar\u00e9chal 2\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" src=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/02\/whatsapp-image-2025-02-26-at-8.49.08-pm.jpeg\" class=\"attachment-medium\" alt=\"\" title=\"WhatsApp Image 2025-02-26 \u00e0 8.49.08 PM\" srcset=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/02\/whatsapp-image-2025-02-26-at-8.49.08-pm.jpeg 1280w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/02\/whatsapp-image-2025-02-26-at-8.49.08-pm-1024x576.jpeg 1024w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/02\/whatsapp-image-2025-02-26-at-8.49.08-pm-18x10.jpeg 18w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"135\" src=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/02\/img-20231005-161755.jpg\" class=\"attachment-medium\" alt=\"\" title=\"IMG_20231005_161755\" srcset=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/02\/img-20231005-161755.jpg 1920w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/02\/img-20231005-161755-1024x461.jpg 1024w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/02\/img-20231005-161755-1536x691.jpg 1536w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/02\/img-20231005-161755-18x8.jpg 18w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"205\" src=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/02\/img-20230801-183145-1.jpg\" class=\"attachment-medium\" alt=\"\" title=\"IMG_20230801_183145 (1)\" srcset=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/02\/img-20230801-183145-1.jpg 1920w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/02\/img-20230801-183145-1-1024x700.jpg 1024w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/02\/img-20230801-183145-1-1536x1050.jpg 1536w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/02\/img-20230801-183145-1-18x12.jpg 18w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/li><\/ul><\/div><\/div><\/div>\n\t<div class=\"wpb_text_column wpb_content_element\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">La perte de biodiversit\u00e9 se manifeste non seulement par la r\u00e9duction des esp\u00e8ces indig\u00e8nes de flore et de faune, mais aussi d'un point de vue \u00e9conomique, car si la monoculture garantit un plus grand volume de production en moins de temps, ce qui permet \u00e0 l'agriculteur d'\u00eatre comp\u00e9titif et d'offrir une plus grande quantit\u00e9 de produits sur le march\u00e9, elle implique \u00e9galement un risque \u00e9lev\u00e9 de pertes consid\u00e9rables si ce syst\u00e8me de culture est affect\u00e9 par des ravageurs ou des facteurs climatiques. Ainsi, en peu de temps, les sols perdent leur fertilit\u00e9 parce qu'ils ne sont pas adapt\u00e9s \u00e0 ces formes de culture et l'agriculteur est contraint d'utiliser des engrais chimiques et d'\u00e9tendre la fronti\u00e8re agricole. La d\u00e9pendance \u00e0 l'\u00e9gard d'une monoculture porte atteinte \u00e0 la souverainet\u00e9 alimentaire des familles.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">La gestion ancestrale \u00e9quilibr\u00e9e de la for\u00eat est m\u00e9connue et la seule alternative est d'utiliser des techniques occidentales qui d\u00e9t\u00e9riorent la biodiversit\u00e9. Par exemple, cultiver du manioc, des piments et des tomates dans le m\u00eame espace permet de mieux conserver le sol que de planter uniquement de la naranjilla et d'attendre la r\u00e9colte sans autre alternative.\u00a0\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Le travail de la terre demande beaucoup de temps et de patience, et les b\u00e9n\u00e9fices ne sont pas toujours \u00e9quitables. L'une des caract\u00e9ristiques est l'abandon des terres en raison des migrations externes et internes, qui conduit \u00e0 une vente de plus en plus rotative des terres qui n'est pas ancr\u00e9e dans la valeur r\u00e9elle qui pourrait \u00eatre g\u00e9n\u00e9r\u00e9e. Par exemple, un propri\u00e9taire vend un hectare de terre pour 1 000 USD, le nouveau propri\u00e9taire plante des pommes de terre chinoises et doit couper la for\u00eat, la r\u00e9colte peut rapporter trois fois, mais la quatri\u00e8me fois, il devra utiliser des pesticides ; et la p\u00e9riode de croissance de quatre mois ralentira, car les pluies arrivent et \u00e9rodent le sol sans la protection d'autres esp\u00e8ces de plantes.\u00a0\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Zanja Arajuno cherche \u00e0 proposer des alternatives \u00e0 la perte de biodiversit\u00e9, gr\u00e2ce \u00e0 son exp\u00e9rience sur le terrain.\u00a0 <\/span><span style=\"font-weight: 400;\">une approche plus holistique, utilisant les arts et l'\u00e9ducation \u00e0 l'environnement comme principaux outils. <\/span><span style=\"font-weight: 400;\">\u00a0<\/span><span style=\"font-weight: 400;\">Gr\u00e2ce \u00e0 l'autogestion, aux mingas et au travail de notre communaut\u00e9 de b\u00e9n\u00e9voles, un chakra a \u00e9t\u00e9 mis en place. <\/span><span style=\"font-weight: 400;\">\u00a0<\/span><span style=\"font-weight: 400;\">(culture ancestrale) pour la durabilit\u00e9 alimentaire de la r\u00e9serve (actuellement, il y a une serre qui est en cours d'installation). <\/span><span style=\"font-weight: 400;\">\u00a0<\/span><span style=\"font-weight: 400;\">il y a dix ans et qui produit : piment, cornichon, tomate, persil de montagne, entre autres) sous l'effet de l'augmentation de la consommation d'\u00e9nergie. <\/span><span style=\"font-weight: 400;\">\u00a0<\/span><span style=\"font-weight: 400;\">la reproduction dans les fermes voisines, pour la subsistance de la famille et des produits diversifi\u00e9s. Il s'agit d'un processus de <\/span><span style=\"font-weight: 400;\">\u00a0<\/span><span style=\"font-weight: 400;\">\u00e0 long terme avec des phases de sensibilisation au niveau local.<\/span><\/p>\n\n\t\t<\/div> \n\t<\/div> <\/div><div class=\"qode-advanced-tab-container\" id=\"tab-misiones-de-biodiversidad-815\" data-icon-pack=\"\" data-icon-html=\"\"><div class=\"qode-advanced-image-gallery  qode-aig-slider-type qode-no-space  qode-image-behavior-lightbox\">\n\t<div class=\"qode-aig-slider qode-owl-slider\" data-number-of-items=\"1\" data-enable-loop=\"yes\" data-enable-autoplay=\"yes\" data-slider-speed=\"5000\" data-slider-speed-animation=\"600\" data-slider-padding=\"no\" data-enable-navigation=\"yes\" data-enable-pagination=\"yes\">\n\t\t\t\t\t<div class=\"qode-aig-image\">\n\t\t\t\t\t\t\t\t\t<a itemprop=\"image\" class=\"qode-aig-lightbox qode-block-drag-link\" href=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2024\/09\/img-20230605-114212.jpg\" data-rel=\"prettyPhoto[image_gallery_pretty_photo-817]\" title=\"IMG_20230605_114212\">\n\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"577\" src=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2024\/09\/img-20230605-114212-1024x577.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2024\/09\/img-20230605-114212-1024x577.jpg 1024w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2024\/09\/img-20230605-114212-1536x865.jpg 1536w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2024\/09\/img-20230605-114212-18x10.jpg 18w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2024\/09\/img-20230605-114212.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t<span class=\"aig-gallery-hover\">\n\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"qode-aig-image\">\n\t\t\t\t\t\t\t\t\t<a itemprop=\"image\" class=\"qode-aig-lightbox qode-block-drag-link\" href=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/02\/dsc03319.jpg\" data-rel=\"prettyPhoto[image_gallery_pretty_photo-817]\" title=\"DSC03319\">\n\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/02\/dsc03319-1024x768.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/02\/dsc03319-1024x768.jpg 1024w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/02\/dsc03319-1536x1152.jpg 1536w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/02\/dsc03319-16x12.jpg 16w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/02\/dsc03319.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t<span class=\"aig-gallery-hover\">\n\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"qode-aig-image\">\n\t\t\t\t\t\t\t\t\t<a itemprop=\"image\" class=\"qode-aig-lightbox qode-block-drag-link\" href=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/02\/anfibios45.jpg\" data-rel=\"prettyPhoto[image_gallery_pretty_photo-817]\" title=\"APPAREIL PHOTO NUM\u00c9RIQUE OLYMPUS\">\n\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/02\/anfibios45-1024x768.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/02\/anfibios45-1024x768.jpg 1024w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/02\/anfibios45-1536x1152.jpg 1536w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/02\/anfibios45-16x12.jpg 16w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/02\/anfibios45.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t<span class=\"aig-gallery-hover\">\n\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"qode-aig-image\">\n\t\t\t\t\t\t\t\t\t<a itemprop=\"image\" class=\"qode-aig-lightbox qode-block-drag-link\" href=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2024\/09\/img-20230605-090108.jpg\" data-rel=\"prettyPhoto[image_gallery_pretty_photo-817]\" title=\"IMG_20230605_090108\">\n\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"577\" src=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2024\/09\/img-20230605-090108-1024x577.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2024\/09\/img-20230605-090108-1024x577.jpg 1024w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2024\/09\/img-20230605-090108-1536x865.jpg 1536w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2024\/09\/img-20230605-090108-18x10.jpg 18w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2024\/09\/img-20230605-090108.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t<span class=\"aig-gallery-hover\">\n\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"qode-aig-image\">\n\t\t\t\t\t\t\t\t\t<a itemprop=\"image\" class=\"qode-aig-lightbox qode-block-drag-link\" href=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/02\/ave.jpg\" data-rel=\"prettyPhoto[image_gallery_pretty_photo-817]\" title=\"ave\">\n\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"726\" src=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/02\/ave-1024x726.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/02\/ave-1024x726.jpg 1024w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/02\/ave-18x12.jpg 18w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/02\/ave.jpg 1472w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t<span class=\"aig-gallery-hover\">\n\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"qode-aig-image\">\n\t\t\t\t\t\t\t\t\t<a itemprop=\"image\" class=\"qode-aig-lightbox qode-block-drag-link\" href=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2024\/09\/img-20230605-093833.jpg\" data-rel=\"prettyPhoto[image_gallery_pretty_photo-817]\" title=\"IMG_2023060605_093833\">\n\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"577\" src=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2024\/09\/img-20230605-093833-1024x577.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2024\/09\/img-20230605-093833-1024x577.jpg 1024w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2024\/09\/img-20230605-093833-1536x865.jpg 1536w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2024\/09\/img-20230605-093833-18x10.jpg 18w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2024\/09\/img-20230605-093833.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t<span class=\"aig-gallery-hover\">\n\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"qode-aig-image\">\n\t\t\t\t\t\t\t\t\t<a itemprop=\"image\" class=\"qode-aig-lightbox qode-block-drag-link\" href=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/02\/369.kl-.jpg\" data-rel=\"prettyPhoto[image_gallery_pretty_photo-817]\" title=\"369.kl\">\n\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/02\/369.kl--1024x683.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/02\/369.kl--1024x683.jpg 1024w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/02\/369.kl--1536x1024.jpg 1536w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/02\/369.kl--18x12.jpg 18w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/02\/369.kl-.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t<span class=\"aig-gallery-hover\">\n\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"qode-aig-image\">\n\t\t\t\t\t\t\t\t\t<a itemprop=\"image\" class=\"qode-aig-lightbox qode-block-drag-link\" href=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/02\/210.-coleoptera-3.jpg\" data-rel=\"prettyPhoto[image_gallery_pretty_photo-817]\" title=\"210. COL\u00c9OPT\u00c8RES (3)\">\n\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/02\/210.-coleoptera-3-1024x768.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/02\/210.-coleoptera-3-1024x768.jpg 1024w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/02\/210.-coleoptera-3-1536x1152.jpg 1536w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/02\/210.-coleoptera-3-16x12.jpg 16w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/02\/210.-coleoptera-3.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t<span class=\"aig-gallery-hover\">\n\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"qode-aig-image\">\n\t\t\t\t\t\t\t\t\t<a itemprop=\"image\" class=\"qode-aig-lightbox qode-block-drag-link\" href=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/02\/river-route.tif\" data-rel=\"prettyPhoto[image_gallery_pretty_photo-817]\" title=\"Route fluviale\">\n\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1\" height=\"1\" src=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/02\/river-route.tif\" class=\"attachment-large size-large\" alt=\"\" \/>\t\t\t\t\t<span class=\"aig-gallery-hover\">\n\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n<\/div>\n\t<div class=\"wpb_text_column wpb_content_element\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"text-align: justify;\">Les<strong> science citoyenne<\/strong> Il s'agit d'une approche dans laquelle la soci\u00e9t\u00e9 civile est activement impliqu\u00e9e dans la recherche scientifique. Elle implique la participation de non-scientifiques \u00e0 des activit\u00e9s scientifiques, telles que la collecte de donn\u00e9es, l'analyse et la diffusion des r\u00e9sultats. Il peut s'agir d'individus, de communaut\u00e9s locales, de groupes d'int\u00e9r\u00eat ou m\u00eame de plateformes en ligne. Cette approche pr\u00e9sente de multiples avantages, tels que l'\u00e9largissement du champ d'application et de la capacit\u00e9 de collecte de donn\u00e9es, la promotion de la culture scientifique et le renforcement du lien entre la science et la soci\u00e9t\u00e9. En outre, elle peut favoriser l'engagement civique et l'autonomisation des communaut\u00e9s locales en leur permettant de prendre des d\u00e9cisions \u00e9clair\u00e9es sur des questions scientifiques et environnementales.<\/p>\n\n\t\t<\/div> \n\t<\/div> <\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div      class=\"vc_row wpb_row section vc_row-fluid  vc_custom_1622158242782 grid_section\" style=' text-align:left;'><div class=\"section_inner clearfix\"><div class='section_inner_margin clearfix'><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div><\/div><\/div><\/div><div      class=\"vc_row wpb_row section vc_row-fluid\" style=' text-align:left;'><div class=\"full_section_inner clearfix\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div><\/div><\/div><div      class=\"vc_row wpb_row section vc_row-fluid\" style=' text-align:left;'><div class=\"full_section_inner clearfix\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div><\/div><\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"MISSIONS DE BIODIVERSITE DEMONSTRATIVE BIBLIOTH\u00c8QUE CONTEXTE La biblioth\u00e8que \"Yachay Wasi\" est une id\u00e9e n\u00e9e de l'amour de la lecture et des livres que Medardo Tapia (son fondateur) manifeste avec passion et inspiration ; l'amour des enfants et l'amour de la...","protected":false},"author":4,"featured_media":784,"parent":0,"menu_order":5,"comment_status":"closed","ping_status":"closed","template":"full_width.php","meta":{"footnotes":""},"class_list":["post-776","page","type-page","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/www.zanjarajuno.org\/fr\/wp-json\/wp\/v2\/pages\/776","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zanjarajuno.org\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.zanjarajuno.org\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.zanjarajuno.org\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zanjarajuno.org\/fr\/wp-json\/wp\/v2\/comments?post=776"}],"version-history":[{"count":69,"href":"https:\/\/www.zanjarajuno.org\/fr\/wp-json\/wp\/v2\/pages\/776\/revisions"}],"predecessor-version":[{"id":1733,"href":"https:\/\/www.zanjarajuno.org\/fr\/wp-json\/wp\/v2\/pages\/776\/revisions\/1733"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zanjarajuno.org\/fr\/wp-json\/wp\/v2\/media\/784"}],"wp:attachment":[{"href":"https:\/\/www.zanjarajuno.org\/fr\/wp-json\/wp\/v2\/media?parent=776"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}