{"id":429,"date":"2021-05-27T16:20:41","date_gmt":"2021-05-27T21:20:41","guid":{"rendered":"https:\/\/www.zanjarajuno.org\/?page_id=429"},"modified":"2025-09-03T16:31:40","modified_gmt":"2025-09-03T21:31:40","slug":"nuestra-historia","status":"publish","type":"page","link":"https:\/\/www.zanjarajuno.org\/fr\/notre-histoire\/","title":{"rendered":"Notre histoire"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><div      class=\"vc_row wpb_row section vc_row-fluid  vc_custom_1622158779402 grid_section\" style=' text-align:left;'><div class=\"section_inner clearfix\"><div class='section_inner_margin clearfix'><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class='q_elements_holder one_column responsive_mode_from_768' ><div class='q_elements_item' data-1280-1440='0px 15% 0px 15%' data-1024-1280='0px 10% 0px 10%' data-animation='no' data-item-class='q_elements_holder_custom_919310'><div class='q_elements_item_inner'><div class='q_elements_item_content q_elements_holder_custom_919310'>\n\t<div class=\"wpb_text_column wpb_content_element\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h2>Un r\u00eave pour d\u00e9fendre l'Amazonie<\/h2>\n<p style=\"text-align: justify;\">Zanja Arajuno a accumul\u00e9 25 ans d'exp\u00e9rience dans le domaine de la faune sauvage, car c'est le r\u00eave de l'ancien Centre Fatima, fond\u00e9 par Medardo Tapia et Ruth Arias, en tant que centre exp\u00e9rimental de l'\u00c9cole polytechnique de Chimborazo et, plus tard, en tant que projet pionnier de l'Organisation des peuples indig\u00e8nes de Pastaza (OPIP) pour la gestion, l'\u00e9levage et la reproduction d'animaux sauvages d'Amazonie sur un territoire conc\u00e9d\u00e9 en commodat par le Conseil provincial de Pastaza. Cet accord a pris fin en 2008.<\/p>\n<p style=\"text-align: justify;\">\u00c0 l'\u00e2ge de 20 ans, Medardo Tapia a eu une vision en ing\u00e9rant du floripondio (wantuk) qui lui montrait un homme sur son dos conduisant divers types d'animaux vers un arbre g\u00e9ant, ressemblant \u00e0 un berger. En tant qu'habitant de Puyo, il a compris que son r\u00eave \u00e9tait la projection de sa vie future dans la d\u00e9fense de l'Amazonie. Medardo avait entendu dire par les anciens ou \"taitas\" que le Sacha Runa est l'esprit protecteur des animaux et il s'est donc senti appel\u00e9 \u00e0 leur venir en aide. En tant qu'agronome, il ne s'occuperait plus des vaches et des moutons, mais des esp\u00e8ces sauvages. C'est ainsi qu'est n\u00e9e la relation avec l'OPIP.<\/p>\n<h3>Pourquoi est-ce important ?<\/h3>\n<p style=\"text-align: justify;\">De toutes les provinces qui composent l'Amazonie \u00e9quatorienne, les provinces d'Orellana et de Pastaza comptent parmi les plus diversifi\u00e9es au monde sur le plan biologique. Dans ces types de for\u00eats tropicales orientales, on trouve environ 150 esp\u00e8ces d'amphibiens, dont certaines sont en danger d'extinction.<\/p>\n<p style=\"text-align: justify;\">Une des particularit\u00e9s du site est qu'il est g\u00e9ographiquement situ\u00e9 dans la bande tampon qui relie le corridor \u00e9cologique OGLAN (provenant de la zone montagneuse d'Arajuno) qui est \u00e9cologiquement important en termes biologiques et scientifiques en raison de la diversit\u00e9 des \u00e9cosyst\u00e8mes qu'il poss\u00e8de, principalement en raison des sources d'eau qui l'entourent. Zanja Arajuno poss\u00e8de une for\u00eat de pi\u00e9mont \u00e0 feuilles persistantes qui abrite des esp\u00e8ces uniques \u00e0 la r\u00e9gion. C'est le cas des populations restantes de l'amphibien arlequin mousseux Atelopus spumarius, une esp\u00e8ce qui a \u00e9t\u00e9 enregistr\u00e9e et \u00e9tudi\u00e9e pendant quelques ann\u00e9es \u00e0 Zanja Arajuno par le biologiste Diego Acosta. Cette esp\u00e8ce est consid\u00e9r\u00e9e comme un indicateur biologique et il est clair que ces populations sont gravement menac\u00e9es d'extinction en raison de la destruction de leurs habitats.<\/p>\n<p style=\"text-align: justify;\">Pastaza abrite 7 des 11 peuples et nationalit\u00e9s indig\u00e8nes de l'\u00c9quateur, ce qui lui conf\u00e8re une richesse et une diversit\u00e9 culturelles uniques dans la r\u00e9gion amazonienne. La relation avec la communaut\u00e9 paysanne et m\u00e9tisse de Mariscal Sucre a favoris\u00e9 l'expansion des zones territoriales avec des possibilit\u00e9s d'intervention \u00e9co-touristique.<\/p>\n\n\t\t<\/div> \n\t<\/div> <\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div      class=\"vc_row wpb_row section vc_row-fluid  vc_custom_1622158242782 grid_section\" style=' text-align:left;'><div class=\"section_inner clearfix\"><div class='section_inner_margin clearfix'><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"qode-advanced-image-gallery  qode-aig-grid-type qode-no-space  qode-image-behavior-lightbox\">\n\t<div class=\"qode-aig-inner qode-outer-space qode-aig-grid qode-aig-three-columns\">\n\t\t\t\t\t<div class=\"qode-aig-image qode-item-space\">\n\t\t\t\t<div class=\"qode-aig-image-inner\">\n\t\t\t\t\t\t\t\t\t\t\t<a itemprop=\"image\" class=\"qode-aig-lightbox\" href=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2024\/05\/MG_3101.jpg\" data-rel=\"prettyPhoto[image_gallery_pretty_photo-758]\" title=\"_MG_3101\">\n\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"681\" src=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2024\/05\/MG_3101-1024x681.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2024\/05\/MG_3101-1024x681.jpg 1024w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2024\/05\/MG_3101-1536x1022.jpg 1536w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2024\/05\/MG_3101-18x12.jpg 18w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2024\/05\/MG_3101.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t<span class=\"aig-gallery-hover\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"qode-aig-image qode-item-space\">\n\t\t\t\t<div class=\"qode-aig-image-inner\">\n\t\t\t\t\t\t\t\t\t\t\t<a itemprop=\"image\" class=\"qode-aig-lightbox\" href=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2024\/05\/MG_3479.jpg\" data-rel=\"prettyPhoto[image_gallery_pretty_photo-758]\" title=\"_MG_3479\">\n\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"681\" src=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2024\/05\/MG_3479-1024x681.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2024\/05\/MG_3479-1024x681.jpg 1024w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2024\/05\/MG_3479-300x200.jpg 300w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2024\/05\/MG_3479-768x511.jpg 768w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2024\/05\/MG_3479-1536x1022.jpg 1536w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2024\/05\/MG_3479-18x12.jpg 18w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2024\/05\/MG_3479-700x466.jpg 700w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2024\/05\/MG_3479.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t<span class=\"aig-gallery-hover\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"qode-aig-image qode-item-space\">\n\t\t\t\t<div class=\"qode-aig-image-inner\">\n\t\t\t\t\t\t\t\t\t\t\t<a itemprop=\"image\" class=\"qode-aig-lightbox\" href=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2024\/05\/MG_3007.jpg\" data-rel=\"prettyPhoto[image_gallery_pretty_photo-758]\" title=\"_MG_3007\">\n\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"681\" src=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2024\/05\/MG_3007-1024x681.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2024\/05\/MG_3007-1024x681.jpg 1024w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2024\/05\/MG_3007-1536x1022.jpg 1536w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2024\/05\/MG_3007-18x12.jpg 18w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2024\/05\/MG_3007.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t<span class=\"aig-gallery-hover\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><div      class=\"vc_row wpb_row section vc_row-fluid  vc_custom_1622150219554 grid_section\" style=' text-align:center;'><div class=\"section_inner clearfix\"><div class='section_inner_margin clearfix'><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><a  itemprop=\"url\" href=\"https:\/\/www.zanjarajuno.org\/fr\/notre-mission\/\" target=\"_self\" data-hover-background-color=\"rgba(255,255,255,0.01)\" data-hover-border-color=\"#000000\" class=\"qbutton  small default\" style=\"\">Notre mission<\/a><\/div><\/div><\/div><\/div><\/div><\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"Un r\u00eave pour d\u00e9fendre l'Amazonie Zanja Arajuno a accumul\u00e9 une exp\u00e9rience de 25 ans de travail avec la faune sauvage. C'est le r\u00eave continu de l'ancien Centro F\u00e1tima, fond\u00e9 par Medardo Tapia et Ruth Arias, en tant que centre exp\u00e9rimental de l'Escuela Polit\u00e9cnica...","protected":false},"author":4,"featured_media":954,"parent":0,"menu_order":1,"comment_status":"closed","ping_status":"closed","template":"full_width.php","meta":{"footnotes":""},"class_list":["post-429","page","type-page","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/www.zanjarajuno.org\/fr\/wp-json\/wp\/v2\/pages\/429","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zanjarajuno.org\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.zanjarajuno.org\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.zanjarajuno.org\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zanjarajuno.org\/fr\/wp-json\/wp\/v2\/comments?post=429"}],"version-history":[{"count":29,"href":"https:\/\/www.zanjarajuno.org\/fr\/wp-json\/wp\/v2\/pages\/429\/revisions"}],"predecessor-version":[{"id":1728,"href":"https:\/\/www.zanjarajuno.org\/fr\/wp-json\/wp\/v2\/pages\/429\/revisions\/1728"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zanjarajuno.org\/fr\/wp-json\/wp\/v2\/media\/954"}],"wp:attachment":[{"href":"https:\/\/www.zanjarajuno.org\/fr\/wp-json\/wp\/v2\/media?parent=429"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}