{"id":791,"date":"2021-08-19T10:43:49","date_gmt":"2021-08-19T15:43:49","guid":{"rendered":"https:\/\/www.zanjarajuno.org\/?page_id=791"},"modified":"2026-08-21T17:15:29","modified_gmt":"2026-08-21T22:15:29","slug":"nuestro-espacio","status":"publish","type":"page","link":"https:\/\/www.zanjarajuno.org\/de\/unser-raum\/","title":{"rendered":"Unser Raum"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><div      class=\"vc_row wpb_row section vc_row-fluid  vc_custom_1622158779402 grid_section\" style=' text-align:left;'><div class=\"section_inner clearfix\"><div class='section_inner_margin clearfix'><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class='q_elements_holder one_column responsive_mode_from_768' ><div class='q_elements_item' data-1280-1440='0px 15% 0px 15%' data-1024-1280='0px 10% 0px 10%' data-animation='no' data-item-class='q_elements_holder_custom_198242'><div class='q_elements_item_inner'><div class='q_elements_item_content q_elements_holder_custom_198242'>\n\t<div class=\"wpb_text_column wpb_content_element\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h2 style=\"font-size: 0.0001pt;\">uestro espacio<\/h2>\n<h3>Un espacio para vivir, aprender y conectar con la selva<\/h3>\n<p class=\"isSelectedEnd\" style=\"text-align: justify;\">El <strong>\u00d6kologisches Zentrum Zanja Arajuno<\/strong> cuenta con <strong>52 hect\u00e1reas de bosque natural<\/strong>, un verdadero laboratorio vivo donde la naturaleza se convierte en un espacio para la investigaci\u00f3n, la educaci\u00f3n ambiental, la conservaci\u00f3n y el encuentro con quienes desean conocer y aprender de la Amazon\u00eda.En medio de este entorno se encuentran diversos espacios pensados para brindar una experiencia integral, combinando comodidad, aprendizaje y contacto directo con la naturaleza.<\/p>\n<p class=\"isSelectedEnd\" style=\"text-align: justify;\"><strong>Caba\u00f1a de alojamiento y encuentro<\/strong><\/p>\n<p class=\"isSelectedEnd\" style=\"text-align: justify;\">Disponemos de una amplia caba\u00f1a con capacidad para <strong>18 a 20 personas<\/strong>, equipada para recibir grupos de estudiantes, investigadores, voluntarios, visitantes y organizaciones. Cuenta con <strong>dos ba\u00f1os completos, un ba\u00f1o social, cocina equipada y espacios destinados al descanso y la convivencia<\/strong>. La caba\u00f1a tambi\u00e9n dispone de un <strong>comedor y espacio de lectura y trabajo<\/strong>, que puede adaptarse para talleres, capacitaciones, reuniones y actividades educativas.<\/p>\n<p class=\"isSelectedEnd\" style=\"text-align: justify;\"><strong>Conectividad en medio de la naturaleza<\/strong><\/p>\n<p class=\"isSelectedEnd\" style=\"text-align: justify;\">Contamos con <strong>Wi-Fi<\/strong> que permite mantenerse conectado cuando sea necesario, sin renunciar a la experiencia de estar inmerso en la selva. Es un espacio pensado para quienes necesitan combinar trabajo, estudio o investigaci\u00f3n con el disfrute de un entorno natural.<\/p>\n<p class=\"isSelectedEnd\" style=\"text-align: justify;\"><strong>Sachateca Yachay Wasi \u2013 Biblioteca comunitaria<\/strong><\/p>\n<p class=\"isSelectedEnd\" style=\"text-align: justify;\">Dentro del Centro Ecol\u00f3gico Zanja Arajuno se encuentra la <strong>Sachateca Yachay Wasi<\/strong>, una biblioteca comunitaria al servicio del sector rural principalmente. M\u00e1s que una biblioteca es tambi\u00e9n parte de nuestro encuentro de saberes, un espacio seguro donde se han realizado talleres de agroecolog\u00eda, teatro de sombras, violencia de g\u00e9nero,\u00a0 edu-comunicaci\u00f3n, adem\u00e1s de mediaci\u00f3n lectora para diversos grupos. Es un espacio abierto al conocimiento, la lectura y el encuentro, donde visitantes, estudiantes y comunidades pueden acercarse a los libros, descubrir nuevas historias y disfrutar de la lectura en medio de la naturaleza.<\/p>\n<p class=\"isSelectedEnd\" style=\"text-align: justify;\"><strong>Choza de fogata y encuentro<\/strong><\/p>\n<p class=\"isSelectedEnd\" style=\"text-align: justify;\">Die <strong>choza de fogata<\/strong> es un espacio para compartir, conversar y disfrutar de las noches amaz\u00f3nicas. Alrededor del fuego, el bosque se convierte en escenario para el encuentro, la narraci\u00f3n de historias, actividades culturales y momentos de reflexi\u00f3n.<\/p>\n<p class=\"isSelectedEnd\" style=\"text-align: justify;\"><strong>Senderos, bosque y r\u00edo<\/strong><\/p>\n<p class=\"isSelectedEnd\" style=\"text-align: justify;\">Es posible recorrer diferentes espacios del bosque, caminar por sus senderos, descubrir la diversidad de plantas, hongos y animales, y acercarse al r\u00edo. Cada recorrido ofrece la oportunidad de observar, aprender y comprender la importancia de conservar estos ecosistemas.<\/p>\n<p class=\"isSelectedEnd\" style=\"text-align: justify;\"><strong>Chacra demostrativa y saberes ancestrales<\/strong><\/p>\n<p class=\"isSelectedEnd\" style=\"text-align: justify;\">Die <strong>chacra demostrativa<\/strong> permite conocer pr\u00e1cticas agr\u00edcolas tradicionales y formas ancestrales de aprovechamiento de la selva. Es un espacio de aprendizaje sobre la relaci\u00f3n entre las comunidades amaz\u00f3nicas, los cultivos y el bosque, recuperando conocimientos que forman parte del patrimonio cultural y natural de la regi\u00f3n.<\/p>\n<h3 style=\"text-align: justify;\"><span style=\"font-size: 12pt;\">Una experiencia m\u00e1s all\u00e1 de una visita<\/span><\/h3>\n<p class=\"isSelectedEnd\" style=\"text-align: justify;\">\u00abZanja\u00bb no es solamente un lugar para alojarse, es un suntuario para <strong>aprender haciendo, investigar, compartir conocimientos, acercarse a la cultura amaz\u00f3nica y experimentar la naturaleza de manera respetuosa<\/strong>. Aqu\u00ed cada espacio est\u00e1 pensado para que visitantes, estudiantes, investigadores, voluntarios y comunidades puedan encontrar una conexi\u00f3n diferente con la selva: <strong>un lugar donde el bosque es aula, laboratorio, biblioteca, despertar de conciencia y territorio de encuentro.<\/strong><\/p>\n<h3 style=\"font-size: 0.0001pt;\">Unser Raum<\/h3>\n\n\t\t<\/div> \n\t<\/div> <\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div      class=\"vc_row wpb_row section vc_row-fluid  vc_custom_1622158242782 grid_section\" style=' text-align:left;'><div class=\"section_inner clearfix\"><div class='section_inner_margin clearfix'><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"qode-advanced-image-gallery  qode-aig-slider-type qode-no-space  qode-image-behavior-lightbox\">\n\t<div class=\"qode-aig-slider qode-owl-slider\" data-number-of-items=\"1\" data-enable-loop=\"yes\" data-enable-autoplay=\"yes\" data-slider-speed=\"5000\" data-slider-speed-animation=\"600\" data-slider-padding=\"no\" data-enable-navigation=\"yes\" data-enable-pagination=\"yes\">\n\t\t\t\t\t<div class=\"qode-aig-image\">\n\t\t\t\t\t\t\t\t\t<a itemprop=\"image\" class=\"qode-aig-lightbox qode-block-drag-link\" href=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2024\/05\/IMG_20230807_082749-1-scaled.jpg\" data-rel=\"prettyPhoto[image_gallery_pretty_photo-162]\" title=\"IMG_20230807_082749\">\n\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"577\" src=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2024\/05\/IMG_20230807_082749-1-1024x577.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2024\/05\/IMG_20230807_082749-1-1024x577.jpg 1024w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2024\/05\/IMG_20230807_082749-1-300x169.jpg 300w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2024\/05\/IMG_20230807_082749-1-768x432.jpg 768w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2024\/05\/IMG_20230807_082749-1-1536x865.jpg 1536w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2024\/05\/IMG_20230807_082749-1-2048x1153.jpg 2048w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2024\/05\/IMG_20230807_082749-1-18x10.jpg 18w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2024\/05\/IMG_20230807_082749-1-700x394.jpg 700w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2024\/05\/IMG_20230807_082749-1-539x303.jpg 539w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2024\/05\/IMG_20230807_082749-1-scaled.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t<span class=\"aig-gallery-hover\">\n\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"qode-aig-image\">\n\t\t\t\t\t\t\t\t\t<a itemprop=\"image\" class=\"qode-aig-lightbox qode-block-drag-link\" href=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2024\/05\/selva-1-e1717116620438.jpg\" data-rel=\"prettyPhoto[image_gallery_pretty_photo-162]\" title=\"Anafi 1.3.2\">\n\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"577\" src=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2024\/05\/selva-1-e1717116620438-1024x577.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2024\/05\/selva-1-e1717116620438-1024x577.jpg 1024w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2024\/05\/selva-1-e1717116620438-1536x865.jpg 1536w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2024\/05\/selva-1-e1717116620438-18x10.jpg 18w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2024\/05\/selva-1-e1717116620438.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t<span class=\"aig-gallery-hover\">\n\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"qode-aig-image\">\n\t\t\t\t\t\t\t\t\t<a itemprop=\"image\" class=\"qode-aig-lightbox qode-block-drag-link\" href=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/04\/dsc-0178.jpg\" data-rel=\"prettyPhoto[image_gallery_pretty_photo-162]\" title=\"DSC_0178\">\n\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/04\/dsc-0178-1024x683.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/04\/dsc-0178-1024x683.jpg 1024w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/04\/dsc-0178-1536x1024.jpg 1536w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/04\/dsc-0178-18x12.jpg 18w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2025\/04\/dsc-0178.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t<span class=\"aig-gallery-hover\">\n\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"qode-aig-image\">\n\t\t\t\t\t\t\t\t\t<a itemprop=\"image\" class=\"qode-aig-lightbox qode-block-drag-link\" href=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2026\/08\/img-20250910-115236.jpg\" data-rel=\"prettyPhoto[image_gallery_pretty_photo-162]\" title=\"IMG_20250910_115236\">\n\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2026\/08\/img-20250910-115236-1024x576.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2026\/08\/img-20250910-115236-1024x576.jpg 1024w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2026\/08\/img-20250910-115236-1536x864.jpg 1536w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2026\/08\/img-20250910-115236-18x10.jpg 18w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2026\/08\/img-20250910-115236.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t<span class=\"aig-gallery-hover\">\n\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"qode-aig-image\">\n\t\t\t\t\t\t\t\t\t<a itemprop=\"image\" class=\"qode-aig-lightbox qode-block-drag-link\" href=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2026\/08\/img-20250526-173938.jpg\" data-rel=\"prettyPhoto[image_gallery_pretty_photo-162]\" title=\"IMG_20250526_173938\">\n\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2026\/08\/img-20250526-173938-1024x576.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2026\/08\/img-20250526-173938-1024x576.jpg 1024w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2026\/08\/img-20250526-173938-1536x864.jpg 1536w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2026\/08\/img-20250526-173938-18x10.jpg 18w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2026\/08\/img-20250526-173938.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t<span class=\"aig-gallery-hover\">\n\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"qode-aig-image\">\n\t\t\t\t\t\t\t\t\t<a itemprop=\"image\" class=\"qode-aig-lightbox qode-block-drag-link\" href=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2026\/08\/img-20250801-175548.jpg\" data-rel=\"prettyPhoto[image_gallery_pretty_photo-162]\" title=\"IMG_20250801_175548\">\n\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2026\/08\/img-20250801-175548-1024x576.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2026\/08\/img-20250801-175548-1024x576.jpg 1024w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2026\/08\/img-20250801-175548-1536x864.jpg 1536w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2026\/08\/img-20250801-175548-18x10.jpg 18w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2026\/08\/img-20250801-175548.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t<span class=\"aig-gallery-hover\">\n\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"qode-aig-image\">\n\t\t\t\t\t\t\t\t\t<a itemprop=\"image\" class=\"qode-aig-lightbox qode-block-drag-link\" href=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2026\/08\/img-20260613-121754.jpg\" data-rel=\"prettyPhoto[image_gallery_pretty_photo-162]\" title=\"IMG_20260613_121754\">\n\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2026\/08\/img-20260613-121754-1024x576.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2026\/08\/img-20260613-121754-1024x576.jpg 1024w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2026\/08\/img-20260613-121754-1536x864.jpg 1536w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2026\/08\/img-20260613-121754-18x10.jpg 18w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2026\/08\/img-20260613-121754.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t<span class=\"aig-gallery-hover\">\n\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"qode-aig-image\">\n\t\t\t\t\t\t\t\t\t<a itemprop=\"image\" class=\"qode-aig-lightbox qode-block-drag-link\" href=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2026\/08\/img-20250302-150722.jpg\" data-rel=\"prettyPhoto[image_gallery_pretty_photo-162]\" title=\"IMG_20250302_150722\">\n\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2026\/08\/img-20250302-150722-1024x576.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2026\/08\/img-20250302-150722-1024x576.jpg 1024w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2026\/08\/img-20250302-150722-1536x864.jpg 1536w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2026\/08\/img-20250302-150722-18x10.jpg 18w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2026\/08\/img-20250302-150722.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t<span class=\"aig-gallery-hover\">\n\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"qode-aig-image\">\n\t\t\t\t\t\t\t\t\t<a itemprop=\"image\" class=\"qode-aig-lightbox qode-block-drag-link\" href=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2024\/05\/IMG-20211213-WA0021.jpg\" data-rel=\"prettyPhoto[image_gallery_pretty_photo-162]\" title=\"IMG-20211213-WA0021\">\n\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2024\/05\/IMG-20211213-WA0021-1024x768.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2024\/05\/IMG-20211213-WA0021-1024x768.jpg 1024w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2024\/05\/IMG-20211213-WA0021-1536x1152.jpg 1536w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2024\/05\/IMG-20211213-WA0021-16x12.jpg 16w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2024\/05\/IMG-20211213-WA0021.jpg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t<span class=\"aig-gallery-hover\">\n\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"qode-aig-image\">\n\t\t\t\t\t\t\t\t\t<a itemprop=\"image\" class=\"qode-aig-lightbox qode-block-drag-link\" href=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2026\/08\/img-20250624-144913.jpg\" data-rel=\"prettyPhoto[image_gallery_pretty_photo-162]\" title=\"IMG_20250624_144913\">\n\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2026\/08\/img-20250624-144913-1024x576.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2026\/08\/img-20250624-144913-1024x576.jpg 1024w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2026\/08\/img-20250624-144913-1536x864.jpg 1536w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2026\/08\/img-20250624-144913-18x10.jpg 18w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2026\/08\/img-20250624-144913.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t<span class=\"aig-gallery-hover\">\n\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"uestro espacio Un espacio para vivir, aprender y conectar con la selva El Centro Ecol\u00f3gico Zanja Arajuno cuenta con 52 hect\u00e1reas de bosque natural, un verdadero laboratorio vivo donde la naturaleza se convierte en un espacio para la investigaci\u00f3n, la educaci\u00f3n ambiental, la conservaci\u00f3n y...","protected":false},"author":4,"featured_media":937,"parent":0,"menu_order":5,"comment_status":"closed","ping_status":"closed","template":"full_width.php","meta":{"footnotes":""},"class_list":["post-791","page","type-page","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/www.zanjarajuno.org\/de\/wp-json\/wp\/v2\/pages\/791","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zanjarajuno.org\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.zanjarajuno.org\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.zanjarajuno.org\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zanjarajuno.org\/de\/wp-json\/wp\/v2\/comments?post=791"}],"version-history":[{"count":18,"href":"https:\/\/www.zanjarajuno.org\/de\/wp-json\/wp\/v2\/pages\/791\/revisions"}],"predecessor-version":[{"id":1795,"href":"https:\/\/www.zanjarajuno.org\/de\/wp-json\/wp\/v2\/pages\/791\/revisions\/1795"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zanjarajuno.org\/de\/wp-json\/wp\/v2\/media\/937"}],"wp:attachment":[{"href":"https:\/\/www.zanjarajuno.org\/de\/wp-json\/wp\/v2\/media?parent=791"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}