{"id":543,"date":"2021-06-10T18:25:28","date_gmt":"2021-06-10T23:25:28","guid":{"rendered":"https:\/\/www.zanjarajuno.org\/?page_id=543"},"modified":"2024-05-30T20:07:33","modified_gmt":"2024-05-31T01:07:33","slug":"comunidad-mariscal-sucre","status":"publish","type":"page","link":"https:\/\/www.zanjarajuno.org\/de\/gemeinde-mariscal-sucre\/","title":{"rendered":"Gemeinde Mariscal Sucre"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><div      class=\"vc_row wpb_row section vc_row-fluid  vc_custom_1622158779402 grid_section\" style=' text-align:left;'><div class=\"section_inner clearfix\"><div class='section_inner_margin clearfix'><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class='q_elements_holder one_column responsive_mode_from_768' ><div class='q_elements_item' data-1280-1440='0px 15% 0px 15%' data-1024-1280='0px 10% 0px 10%' data-animation='no' data-item-class='q_elements_holder_custom_439333'><div class='q_elements_item_inner'><div class='q_elements_item_content q_elements_holder_custom_439333'>\n\t<div class=\"wpb_text_column wpb_content_element\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h2>Die Kinder von Mariscal Sucre<\/h2>\n<p style=\"text-align: justify;\"><strong>\"Ich habe gerade mit meinem Onkel ein Reh gesehen, aber es war ruhig, w\u00e4hrend er zum Gewehr griff, haben ich und die anderen Kinder es erschreckt und es ist schon in den Dschungel gegangen, wir haben es gerettet.\"<\/strong><\/p>\n<p style=\"text-align: justify;\">Ich erinnere mich, dass mein kleiner Sohn, als ich anfing, die Gemeinde zu besuchen (eine Siedlung von Mestizen aus der Provinz Ca\u00f1ar), seine ersten Tage in der Schule erlebte und wie eine Zecke an mir klebte, weil er nicht bei den anderen Kindern oder der Lehrerin bleiben wollte. Nach einer Weile beschloss ich, dass dies ein guter Ort war, um unsere Idee des Umweltschutzes weiterzugeben und in diese wunderbaren kleinen K\u00f6pfe - die in diesem Alter wie Schw\u00e4mme sind - die Idee zu s\u00e4en, den Raum, in dem wir leben, zu sch\u00fctzen und f\u00fcr eine gesunde und gl\u00fcckliche Umwelt zu k\u00e4mpfen.<br \/>\nIch erinnere mich, dass ich ihnen als Erstes etwas \u00fcber die Tiere des Amazonas beigebracht habe, die in unseren W\u00e4ldern leben. Und wenn ich von unseren W\u00e4ldern spreche, dann meine ich nicht nur das Gebiet, das wir als Naturschutzzentrum betreuen, sondern auch die Waldreste, die den Familien dieser Gemeinschaft geh\u00f6ren. Ich werde nie vergessen, wie ich sie fragte, ob sie das Agouti (ein amazonisches Nagetier) kennen, woraufhin ein Junge antwortete, dass er am Wochenende mit seinem Onkel auf die Jagd gegangen sei und ein k\u00f6stliches Essen zubereitet habe. Zu diesem Zeitpunkt waren mein Denken und mein Wissen gereift, und ich verstand ganz klar, dass der Dschungel f\u00fcr die Menschen, die ihn bewohnen (vor allem f\u00fcr die Ureinwohner), die Quelle von Nahrung und Medizin ist und dass das Jagen, Sammeln und die Ausbeutung der nat\u00fcrlichen Ressourcen jahrtausendelang eine Praxis war, die ohne nennenswerte Beeintr\u00e4chtigung der Natur funktionierte. Es war die Entwicklung des Kapitalismus und der Ehrgeiz des Menschen, die unseren V\u00f6lkern Trauer und Leid brachten, ein Ereignis, das vielleicht mit der Eroberung begann, als er begann, mit Blut und Schlamm Reichtum und Kapitalanh\u00e4ufung zu schmieden. Heute ist es das Ungeheuer des Extraktivismus und die Vision des Waldes als \"gr\u00fcne Ware\".<\/p>\n<p style=\"text-align: justify;\">Nun, um auf das Thema zur\u00fcckzukommen, es war interessant und sehr sch\u00f6n, meine Zeit mit den Kindern zu teilen, mit ihnen \u00fcber die verschiedenen Tiere des Dschungels, ihre Funktion im \u00d6kosystem, die Zusammenh\u00e4nge und die Bedeutung ihrer Erhaltung und ihres Schutzes zu sprechen; und nach einem Jahr Arbeit kam eines Tages derselbe Junge, der mir von seiner Jagd mit seinem Onkel erz\u00e4hlt hatte, zu mir gerannt und erz\u00e4hlte mir: Ich habe gerade mit meinem Onkel ein Reh gesehen, aber keine Sorge, w\u00e4hrend er zur Flinte griff, haben ich und die anderen Kinder es erschreckt, und es ist schon in den Wald gegangen, wir haben es gerettet. Wie wunderbar, das sind Ergebnisse, die man nicht in einem offiziellen Bericht festhalten kann, es ist das Leben selbst, das einem diese Tage schenkt, an denen man Fr\u00fcchte erntet und sich ein bisschen gl\u00fccklicher f\u00fchlt. Mehr als 8 Jahre sind bereits vergangen und wir sind gegangen, um diese Leute zu sein, die kommen, um etwas Neues in der Gemeinschaft zu lehren, um Teil der Gemeinschaft zu sein, um stolz \"mariscale\u00f1os\" zu sein, um unsere Erfahrungen zu teilen, um von allen zu lernen, um gemeinsam f\u00fcr unsere Rechte zu k\u00e4mpfen, f\u00fcr unseren Wald, f\u00fcr unser Gl\u00fcck.<\/p>\n<p>(Geschichte: Lucero Mora)<\/p>\n<h3 style=\"font-size: 0.0001pt;\">Die Kinder von Mariscal Sucre<\/h3>\n\n\t\t<\/div> \n\t<\/div> <\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div      class=\"vc_row wpb_row section vc_row-fluid  vc_custom_1622158242782 grid_section\" style=' text-align:left;'><div class=\"section_inner clearfix\"><div class='section_inner_margin clearfix'><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"qode-advanced-image-gallery  qode-aig-grid-type qode-no-space  qode-image-behavior-lightbox\">\n\t<div class=\"qode-aig-inner qode-outer-space qode-aig-grid qode-aig-three-columns\">\n\t\t\t\t\t<div class=\"qode-aig-image qode-item-space\">\n\t\t\t\t<div class=\"qode-aig-image-inner\">\n\t\t\t\t\t\t\t\t\t\t\t<a itemprop=\"image\" class=\"qode-aig-lightbox\" href=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2024\/05\/IMG_20211211_064545.jpg\" data-rel=\"prettyPhoto[image_gallery_pretty_photo-376]\" title=\"dav\">\n\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"577\" src=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2024\/05\/IMG_20211211_064545-1024x577.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2024\/05\/IMG_20211211_064545-1024x577.jpg 1024w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2024\/05\/IMG_20211211_064545-1536x866.jpg 1536w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2024\/05\/IMG_20211211_064545-18x10.jpg 18w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2024\/05\/IMG_20211211_064545.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t<span class=\"aig-gallery-hover\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"qode-aig-image qode-item-space\">\n\t\t\t\t<div class=\"qode-aig-image-inner\">\n\t\t\t\t\t\t\t\t\t\t\t<a itemprop=\"image\" class=\"qode-aig-lightbox\" href=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2024\/05\/P1070217-e1717020995912.jpg\" data-rel=\"prettyPhoto[image_gallery_pretty_photo-376]\" title=\"P1070217\">\n\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"577\" src=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2024\/05\/P1070217-e1717020995912-1024x577.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2024\/05\/P1070217-e1717020995912-1024x577.jpg 1024w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2024\/05\/P1070217-e1717020995912-1536x865.jpg 1536w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2024\/05\/P1070217-e1717020995912-18x10.jpg 18w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2024\/05\/P1070217-e1717020995912.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t<span class=\"aig-gallery-hover\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"qode-aig-image qode-item-space\">\n\t\t\t\t<div class=\"qode-aig-image-inner\">\n\t\t\t\t\t\t\t\t\t\t\t<a itemprop=\"image\" class=\"qode-aig-lightbox\" href=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2024\/05\/20210310_160310-e1717020566866.jpg\" data-rel=\"prettyPhoto[image_gallery_pretty_photo-376]\" title=\"20210310_160310\">\n\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"577\" src=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2024\/05\/20210310_160310-e1717020566866-1024x577.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2024\/05\/20210310_160310-e1717020566866-1024x577.jpg 1024w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2024\/05\/20210310_160310-e1717020566866-1536x865.jpg 1536w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2024\/05\/20210310_160310-e1717020566866-18x10.jpg 18w, https:\/\/www.zanjarajuno.org\/wp-content\/uploads\/2024\/05\/20210310_160310-e1717020566866.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t<span class=\"aig-gallery-hover\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"Die Kinder von Mariscal Sucre \"Ich habe gerade mit meinem Onkel ein Reh gesehen, aber keine Sorge, w\u00e4hrend er zum Gewehr griff, haben ich und die anderen Kinder es erschreckt und es ist schon in den Dschungel gegangen, wir haben es gerettet\". Ich erinnere mich, als ich anfing, die...","protected":false},"author":4,"featured_media":549,"parent":0,"menu_order":2,"comment_status":"closed","ping_status":"closed","template":"full_width.php","meta":{"footnotes":""},"class_list":["post-543","page","type-page","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/www.zanjarajuno.org\/de\/wp-json\/wp\/v2\/pages\/543","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zanjarajuno.org\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.zanjarajuno.org\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.zanjarajuno.org\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zanjarajuno.org\/de\/wp-json\/wp\/v2\/comments?post=543"}],"version-history":[{"count":9,"href":"https:\/\/www.zanjarajuno.org\/de\/wp-json\/wp\/v2\/pages\/543\/revisions"}],"predecessor-version":[{"id":1236,"href":"https:\/\/www.zanjarajuno.org\/de\/wp-json\/wp\/v2\/pages\/543\/revisions\/1236"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zanjarajuno.org\/de\/wp-json\/wp\/v2\/media\/549"}],"wp:attachment":[{"href":"https:\/\/www.zanjarajuno.org\/de\/wp-json\/wp\/v2\/media?parent=543"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}